{"id":29828,"date":"2025-04-16T12:38:49","date_gmt":"2025-04-16T10:38:49","guid":{"rendered":"https:\/\/construccionesmarva.com\/?page_id=75"},"modified":"2025-09-25T10:29:04","modified_gmt":"2025-09-25T08:29:04","slug":"portada","status":"publish","type":"page","link":"https:\/\/construccionesmarva.com\/es\/","title":{"rendered":"Portada"},"content":{"rendered":"<p>[vc_row][vc_column]\n\t\t\t<!-- START Conoce Marva 11 REVOLUTION SLIDER 6.1.5 --><p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t<rs-module-wrap id=\"rev_slider_45_1_wrapper\" data-source=\"gallery\" style=\"background:transparent;padding:0;\">\n\t\t\t\t<rs-module id=\"rev_slider_45_1\" style=\"display:none;\" data-version=\"6.1.5\">\n\t\t\t\t\t<rs-slides>\n\t\t\t\t\t\t<rs-slide data-key=\"rs-142\" data-title=\"Slide\" data-duration=\"7000\" data-anim=\"ei:d;eo:d;s:800;r:0;t:slideleft;sl:7;\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" src=\"\/\/construccionesmarva.com\/wp-content\/plugins\/revslider\/public\/assets\/assets\/dummy.png\" alt=\"slider portada 2 scaled\" title=\"slider portada 2 scaled\" width=\"2560\" height=\"1424\" data-lazyload=\"\/\/construccionesmarva.com\/wp-content\/uploads\/2017\/05\/slider-portada-2-scaled.jpg\" data-parallax=\"5\" class=\"rev-slidebg\" data-no-retina>\n\t\t\t\t\t\t\t<rs-bgvideo \n\t\t\t\t\t\t\t\tdata-video=\"w:100%;h:100%;sta:00:05;end:01:40;nse:false;l:true;ptimer:false;\"\n\t\t\t\t\t\t\t\tdata-mp4=\"\/\/construccionesmarva.es\/wp-content\/uploads\/2017\/05\/Marva-Construcciones.mp4\"\n\t\t\t\t\t\t\t><\/rs-bgvideo>\n<!--\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-45-slide-142-layer-9\" \n\t\t\t\t\t\t\t\tclass=\"tp-shape tp-shapewrapper\"\n\t\t\t\t\t\t\t\tdata-type=\"shape\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:100px;y:m;yo:-250px;\"\n\t\t\t\t\t\t\t\tdata-text=\"fw:700;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:270px;h:5px;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"x:-100%;o:1;tp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_0_mask=\"u:t;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"tp:600;sp:1000;sR:10;\"\n\t\t\t\t\t\t\t\tdata-frame_1_mask=\"u:t;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;tp:600;e:nothing;st:6930;sR:5920;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:8;background-color:rgb(148, 20, 62);\"\n\t\t\t\t\t\t\t> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-45-slide-142-layer-12\" \n\t\t\t\t\t\t\t\tclass=\"tp-shape tp-shapewrapper\"\n\t\t\t\t\t\t\t\tdata-type=\"shape\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:364px;y:m;yo:19px;\"\n\t\t\t\t\t\t\t\tdata-text=\"fw:700;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:5px;h:541px;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"y:-100%;o:1;tp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_0_mask=\"u:t;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"tp:600;st:600;sp:1000;sR:600;\"\n\t\t\t\t\t\t\t\tdata-frame_1_mask=\"u:t;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;tp:600;e:nothing;st:6930;sR:5330;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:9;background-color:#94143e;\"\n\t\t\t\t\t\t\t> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-45-slide-142-layer-14\" \n\t\t\t\t\t\t\t\tclass=\"tp-shape tp-shapewrapper\"\n\t\t\t\t\t\t\t\tdata-type=\"shape\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:100px;y:m;yo:289px;\"\n\t\t\t\t\t\t\t\tdata-text=\"fw:700;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:270px;h:5px;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"x:100%;o:1;tp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_0_mask=\"u:t;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"tp:600;st:1200;sp:1000;sR:1200;\"\n\t\t\t\t\t\t\t\tdata-frame_1_mask=\"u:t;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;tp:600;e:nothing;st:6930;sR:4730;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:10;background-color:#94143e;\"\n\t\t\t\t\t\t\t> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-45-slide-142-layer-15\" \n\t\t\t\t\t\t\t\tclass=\"tp-shape tp-shapewrapper\"\n\t\t\t\t\t\t\t\tdata-type=\"shape\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:100px;y:m;yo:20px;\"\n\t\t\t\t\t\t\t\tdata-text=\"fw:700;\"\n\t\t\t\t\t\t\t\tdata-dim=\"w:5px;h:540px;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"y:100%;tp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_0_mask=\"u:t;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"tp:600;st:1800;sp:1000;sR:1800;\"\n\t\t\t\t\t\t\t\tdata-frame_1_mask=\"u:t;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"o:0;tp:600;e:nothing;st:6930;sR:4130;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:11;background-color:#94143e;\"\n\t\t\t\t\t\t\t> \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-45-slide-142-layer-16\" \n\t\t\t\t\t\t\t\tclass=\"slider-title\"\n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:156px;y:m;yo:0,-30px,-30px,-30px;\"\n\t\t\t\t\t\t\t\tdata-text=\"s:72,63,57,50;l:72,68,62,54;fw:600;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"x:-150px;tp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"tp:600;e:Power2.easeInOut;st:700;sp:1500;sR:700;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"y:100%;tp:600;e:Power2.easeInOut;st:5340;sp:1610;sR:3140;\"\n\t\t\t\t\t\t\t\tdata-frame_999_mask=\"u:t;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:12;font-family:'Poppins',sans-serif;\"\n\t\t\t\t\t\t\t>Somos<br>los embajadores<br>de tu hogar \n\t\t\t\t\t\t\t<\/rs-layer><!--\n\n\t\t\t\t\t\t\t--><rs-layer\n\t\t\t\t\t\t\t\tid=\"slider-45-slide-142-layer-18\" \n\t\t\t\t\t\t\t\tclass=\"slider-title\"\n\t\t\t\t\t\t\t\tdata-type=\"text\"\n\t\t\t\t\t\t\t\tdata-rsp_ch=\"on\"\n\t\t\t\t\t\t\t\tdata-xy=\"xo:156px;y:m;yo:-170px;\"\n\t\t\t\t\t\t\t\tdata-text=\"s:18;l:20;ls:0.1em !important;\"\n\t\t\t\t\t\t\t\tdata-frame_0=\"x:155%;o:1;tp:600;\"\n\t\t\t\t\t\t\t\tdata-frame_0_mask=\"u:t;x:50px;\"\n\t\t\t\t\t\t\t\tdata-frame_1=\"tp:600;e:Power2.easeInOut;st:1000;sp:2000;sR:1000;\"\n\t\t\t\t\t\t\t\tdata-frame_1_mask=\"u:t;\"\n\t\t\t\t\t\t\t\tdata-frame_999=\"y:100%;tp:600;e:Power1.easeOut;st:5130;sp:1410;sR:2130;\"\n\t\t\t\t\t\t\t\tdata-frame_999_mask=\"u:t;\"\n\t\t\t\t\t\t\t\tstyle=\"z-index:13;font-family:'Poppins',sans-serif;font-weight:600;text-transform:uppercase;\"\n\t\t\t\t\t\t\t>Marva Construcciones & ventas.<br>\nEmpresa l\u00edder en construcci\u00f3n de viviendas en Moraira \n\t\t\t\t\t\t\t<\/rs-layer><!--\n-->\t\t\t\t\t\t<\/rs-slide>\n\t\t\t\t\t<\/rs-slides>\n\t\t\t\t\t<rs-progress class=\"rs-bottom\" style=\"visibility: hidden !important;\"><\/rs-progress>\n\t\t\t\t<\/rs-module>\n\t\t\t\t<script type=\"text\/javascript\">\n\t\t\t\t\tsetREVStartSize({c: 'rev_slider_45_1',rl:[2048,1600,1260,992],el:[800,800,800,800],gw:[1370,1100,900,700],gh:[800,800,800,800],layout:'fullscreen',offsetContainer:'.navbar',offset:'',mh:\"380\"});\n\t\t\t\t\tvar\trevapi45,\n\t\t\t\t\t\ttpj;\n\t\t\t\t\tjQuery(function() {\n\t\t\t\t\t\ttpj = jQuery;\n\t\t\t\t\t\tif(tpj(\"#rev_slider_45_1\").revolution == undefined){\n\t\t\t\t\t\t\trevslider_showDoubleJqueryError(\"#rev_slider_45_1\");\n\t\t\t\t\t\t}else{\n\t\t\t\t\t\t\trevapi45 = tpj(\"#rev_slider_45_1\").show().revolution({\n\t\t\t\t\t\t\t\tjsFileLocation:\"\/\/construccionesmarva.com\/wp-content\/plugins\/revslider\/public\/assets\/js\/\",\n\t\t\t\t\t\t\t\tsliderLayout:\"fullscreen\",\n\t\t\t\t\t\t\t\tduration:7000,\n\t\t\t\t\t\t\t\tvisibilityLevels:\"2048,1600,1260,992\",\n\t\t\t\t\t\t\t\tgridwidth:\"1370,1100,900,700\",\n\t\t\t\t\t\t\t\tgridheight:\"800,800,800,800\",\n\t\t\t\t\t\t\t\tminHeight:380,\n\t\t\t\t\t\t\t\tautoHeight:true,\n\t\t\t\t\t\t\t\tlazyType:\"smart\",\n\t\t\t\t\t\t\t\teditorheight:\"800,800,800,800\",\n\t\t\t\t\t\t\t\tresponsiveLevels:\"2048,1600,1260,992\",\n\t\t\t\t\t\t\t\tfullScreenOffsetContainer:\".navbar\",\n\t\t\t\t\t\t\t\tdisableProgressBar:\"on\",\n\t\t\t\t\t\t\t\tnavigation: {\n\t\t\t\t\t\t\t\t\tmouseScrollNavigation:false,\n\t\t\t\t\t\t\t\t\ttouch: {\n\t\t\t\t\t\t\t\t\t\ttouchenabled:true\n\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\tparallax: {\n\t\t\t\t\t\t\t\t\tlevels:[5,10,15,20,25,30,35,40,45,50,47,48,49,50,51,55],\n\t\t\t\t\t\t\t\t\ttype:\"scroll\",\n\t\t\t\t\t\t\t\t\torigo:\"slidercenter\",\n\t\t\t\t\t\t\t\t\tspeed:300,\n\t\t\t\t\t\t\t\t\tdisable_onmobile:true\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t\tfallbacks: {\n\t\t\t\t\t\t\t\t\tallowHTML5AutoPlayOnAndroid:true\n\t\t\t\t\t\t\t\t},\n\t\t\t\t\t\t\t});\n\t\t\t\t\t\t\tvar slider = revapi45;\n\njQuery('.arrow-left').on('click', function () {\n    slider.revprev();\n});\njQuery('.arrow-right').on('click', function () {\n    slider.revnext();\n});\n\t\t\t\t\t\t}\n\t\t\t\t\t\t\n\t\t\t\t\t});\n\t\t\t\t<\/script>\n\t\t\t<\/rs-module-wrap>\n\t\t\t<!-- END REVOLUTION SLIDER -->\n[vc_column_text css=&#8221;.vc_custom_1756291540809{padding-top: 20px !important;padding-bottom: 20px !important;}&#8221;]<\/p>\n<h1>Construcciones Marva<\/h1>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1606122517999{background-color: #efefef !important;}&#8221;][vc_column offset=&#8221;vc_hidden-lg&#8221;]    <div class=\"  \">\n        <main class=\"page-header\">\n            <div class=\"container\"><h2>\u00daltimos Proyectos<\/h2><\/div>\n        <\/main>\n\n        <div class=\"content  \">\n            <div class=\"projects\">\n                <div class=\"container\">\n                    <div class=\"filter-content-2\">\n                        <ul class=\"filter js-filter\">\n                            <li class=\"active\"><a href=\"#\"\n                                                  data-filter=\"*\">Todos los tipos de proyecto<\/a><\/li>\n\n\t\t\t\t\t\t\t                                    <li><a href=\"#\"\n                                           data-filter=\".nueva-construccion\">Nueva Construcci\u00f3n <\/a>\n                                    <\/li>\n\t\t\t\t\t\t\t\t\t                                    <li><a href=\"#\"\n                                           data-filter=\".nuevos-proyectos-a-la-venta\">Nuevos Proyectos a la Venta <\/a>\n                                    <\/li>\n\t\t\t\t\t\t\t\t\t                                    <li><a href=\"#\"\n                                           data-filter=\".reformas\">Reformas <\/a>\n                                    <\/li>\n\t\t\t\t\t\t\t\t\t                        <\/ul>\n                    <\/div>\n                <\/div>\n                <div class=\"grid-items js-isotope js-grid-items\">\n\n\t\t\t\t\t\n                                <div style=\"cursor: pointer;\"\n                                     onclick=\"window.location = 'https:\/\/construccionesmarva.com\/es\/projects\/villa-sorell\/'\"\n                                     class=\"grid-item nuevos-proyectos-a-la-venta js-isotope-item js-grid-item\">\n                                    <div class=\"project-item item-shadow\">\n                                        <img decoding=\"async\" alt=\"Sorell1\" class=\"img-responsive\"\n                                             src=\"https:\/\/construccionesmarva.com\/wp-content\/uploads\/2026\/03\/sorell1-425x573.png\">\n                                        <div class=\"project-hover\">\n                                            <div class=\"project-hover-content\">\n                                                <h3 class=\"project-title\">Villa Sorell<\/h3>\n                                                <p class=\"project-description\">Descubre esta fant\u00e1stica vivienda situada en la calle T\u00f2tina, 6 en Benissa, en una zona tranquila y muy cercana al mar. La propiedad se encuentra a solo 500 metros de la preciosa Cala Baladrar, lo que permite llegar en 2 minutos en coche o aproximadamente 7 minutos caminando.\r\n\r\nLa vivienda se...<\/p>\n                                            <\/div>\n                                        <\/div>\n                                        <a href=\"https:\/\/construccionesmarva.com\/es\/projects\/villa-sorell\/\"\n                                           class=\"link-arrow\">Ver proyecto <i class=\"icon ion-ios-arrow-right\"><\/i><\/a>\n                                    <\/div>\n                                <\/div>\n\n\n\t\t\t\t\t\t\t\n                                <div style=\"cursor: pointer;\"\n                                     onclick=\"window.location = 'https:\/\/construccionesmarva.com\/es\/projects\/villa-giulia\/'\"\n                                     class=\"grid-item nuevos-proyectos-a-la-venta js-isotope-item js-grid-item\">\n                                    <div class=\"project-item item-shadow\">\n                                        <img decoding=\"async\" alt=\"Villa Gulia 1 1\" class=\"img-responsive\"\n                                             src=\"https:\/\/construccionesmarva.com\/wp-content\/uploads\/2024\/03\/Villa-Gulia-1-1-425x573.png\">\n                                        <div class=\"project-hover\">\n                                            <div class=\"project-hover-content\">\n                                                <h3 class=\"project-title\">Villa Giulia<\/h3>\n                                                <p class=\"project-description\">\u00a1Descubre esta magn\u00edfica residencia en la calle Alcalal\u00ed de Moraira, una joya en la zona alta de El Portet de Moraira!\r\n\r\nCon una ubicaci\u00f3n privilegiada a solo 2.7 km de la playa del Portet, esta impresionante casa de dise\u00f1o ofrece la combinaci\u00f3n perfecta de lujo y comodidad. Situada en una sola...<\/p>\n                                            <\/div>\n                                        <\/div>\n                                        <a href=\"https:\/\/construccionesmarva.com\/es\/projects\/villa-giulia\/\"\n                                           class=\"link-arrow\">Ver proyecto <i class=\"icon ion-ios-arrow-right\"><\/i><\/a>\n                                    <\/div>\n                                <\/div>\n\n\n\t\t\t\t\t\t\t\n                                <div style=\"cursor: pointer;\"\n                                     onclick=\"window.location = 'https:\/\/construccionesmarva.com\/es\/projects\/villa-sauce\/'\"\n                                     class=\"grid-item nuevos-proyectos-a-la-venta js-isotope-item js-grid-item\">\n                                    <div class=\"project-item item-shadow\">\n                                        <img decoding=\"async\" alt=\"Sauce 4\" class=\"img-responsive\"\n                                             src=\"https:\/\/construccionesmarva.com\/wp-content\/uploads\/2026\/03\/Sauce-4-425x573.jpg\">\n                                        <div class=\"project-hover\">\n                                            <div class=\"project-hover-content\">\n                                                <h3 class=\"project-title\">Villa Sauce<\/h3>\n                                                <p class=\"project-description\">Te presentamos la vivienda en construcci\u00f3n en la \u00a0calle Sauce, 4 de Moraira.\r\n\r\nSituada a solo 2,5 km de la playa y del encantador pueblo, esta residencia promete combinar comodidad, estilo y ubicaci\u00f3n privilegiada.\r\n\r\n\r\nCon una distribuci\u00f3n en tres plantas, esta casa ofrece un dise\u00f1o moderno y funcional.\r\n\r\nEn la primera planta, te...<\/p>\n                                            <\/div>\n                                        <\/div>\n                                        <a href=\"https:\/\/construccionesmarva.com\/es\/projects\/villa-sauce\/\"\n                                           class=\"link-arrow\">Ver proyecto <i class=\"icon ion-ios-arrow-right\"><\/i><\/a>\n                                    <\/div>\n                                <\/div>\n\n\n\t\t\t\t\t\t\t\n                                <div style=\"cursor: pointer;\"\n                                     onclick=\"window.location = 'https:\/\/construccionesmarva.com\/es\/projects\/villa-sara\/'\"\n                                     class=\"grid-item nueva-construccion js-isotope-item js-grid-item\">\n                                    <div class=\"project-item item-shadow\">\n                                        <img decoding=\"async\" alt=\"Diseno Sin Titulo 32 1\" class=\"img-responsive\"\n                                             src=\"https:\/\/construccionesmarva.com\/wp-content\/uploads\/2017\/05\/Diseno-sin-titulo-32-1-425x573.png\">\n                                        <div class=\"project-hover\">\n                                            <div class=\"project-hover-content\">\n                                                <h3 class=\"project-title\">Villa Sara<\/h3>\n                                                <p class=\"project-description\">Te damos la bienvenida a esta impresionante villa en primera l\u00ednea de playa, donde el dise\u00f1o y la elegancia se combinan perfectamente con la belleza del mar. Construida en 2023, esta residencia vacacional ofrece una experiencia \u00fanica en la Playa de Calpe, Costa Blanca. Presenta un dise\u00f1o moderno ofreciendo espacios...<\/p>\n                                            <\/div>\n                                        <\/div>\n                                        <a href=\"https:\/\/construccionesmarva.com\/es\/projects\/villa-sara\/\"\n                                           class=\"link-arrow\">Ver proyecto <i class=\"icon ion-ios-arrow-right\"><\/i><\/a>\n                                    <\/div>\n                                <\/div>\n\n\n\t\t\t\t\t\t\t\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n\t[vc_column_text]<\/p>\n<h2 style=\"text-align: right; font-size: 1.285rem;\"><a href=\"https:\/\/construccionesmarva.com\/es\/proyectos\/\">VER TODOS LOS PROYECTOS<\/a><\/h2>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1606122517999{background-color: #efefef !important;}&#8221;][vc_column offset=&#8221;vc_hidden-md vc_hidden-sm vc_hidden-xs&#8221;]    <div class=\"  \">\n        <main class=\"page-header\">\n            <div class=\"container\"><h2>\u00daltimos Proyectos<\/h2><\/div>\n        <\/main>\n\n        <div class=\"content  \">\n            <div class=\"projects\">\n                <div class=\"container\">\n                    <div class=\"filter-content-2\">\n                        <ul class=\"filter js-filter\">\n                            <li class=\"active\"><a href=\"#\"\n                                                  data-filter=\"*\">Todos los tipos de proyecto<\/a><\/li>\n\n\t\t\t\t\t\t\t                                    <li><a href=\"#\"\n                                           data-filter=\".nueva-construccion\">Nueva Construcci\u00f3n <\/a>\n                                    <\/li>\n\t\t\t\t\t\t\t\t\t                                    <li><a href=\"#\"\n                                           data-filter=\".nuevos-proyectos-a-la-venta\">Nuevos Proyectos a la Venta <\/a>\n                                    <\/li>\n\t\t\t\t\t\t\t\t\t                                    <li><a href=\"#\"\n                                           data-filter=\".reformas\">Reformas <\/a>\n                                    <\/li>\n\t\t\t\t\t\t\t\t\t                        <\/ul>\n                    <\/div>\n                <\/div>\n                <div class=\"grid-items js-isotope js-grid-items\">\n\n\t\t\t\t\t\n                                <div style=\"cursor: pointer;\"\n                                     onclick=\"window.location = 'https:\/\/construccionesmarva.com\/es\/projects\/villa-sorell\/'\"\n                                     class=\"grid-item nuevos-proyectos-a-la-venta js-isotope-item js-grid-item\">\n                                    <div class=\"project-item item-shadow\">\n                                        <img decoding=\"async\" alt=\"Sorell1\" class=\"img-responsive\"\n                                             src=\"https:\/\/construccionesmarva.com\/wp-content\/uploads\/2026\/03\/sorell1-425x573.png\">\n                                        <div class=\"project-hover\">\n                                            <div class=\"project-hover-content\">\n                                                <h3 class=\"project-title\">Villa Sorell<\/h3>\n                                                <p class=\"project-description\">Descubre esta fant\u00e1stica vivienda situada en la calle T\u00f2tina, 6 en Benissa, en una zona tranquila y muy cercana al mar. La propiedad se encuentra a solo 500 metros de la preciosa Cala Baladrar, lo que permite llegar en 2 minutos en coche o aproximadamente 7 minutos caminando.\r\n\r\nLa vivienda se...<\/p>\n                                            <\/div>\n                                        <\/div>\n                                        <a href=\"https:\/\/construccionesmarva.com\/es\/projects\/villa-sorell\/\"\n                                           class=\"link-arrow\">Ver proyecto <i class=\"icon ion-ios-arrow-right\"><\/i><\/a>\n                                    <\/div>\n                                <\/div>\n\n\n\t\t\t\t\t\t\t\n                                <div style=\"cursor: pointer;\"\n                                     onclick=\"window.location = 'https:\/\/construccionesmarva.com\/es\/projects\/villa-giulia\/'\"\n                                     class=\"grid-item nuevos-proyectos-a-la-venta js-isotope-item js-grid-item\">\n                                    <div class=\"project-item item-shadow\">\n                                        <img decoding=\"async\" alt=\"Villa Gulia 1 1\" class=\"img-responsive\"\n                                             src=\"https:\/\/construccionesmarva.com\/wp-content\/uploads\/2024\/03\/Villa-Gulia-1-1-425x573.png\">\n                                        <div class=\"project-hover\">\n                                            <div class=\"project-hover-content\">\n                                                <h3 class=\"project-title\">Villa Giulia<\/h3>\n                                                <p class=\"project-description\">\u00a1Descubre esta magn\u00edfica residencia en la calle Alcalal\u00ed de Moraira, una joya en la zona alta de El Portet de Moraira!\r\n\r\nCon una ubicaci\u00f3n privilegiada a solo 2.7 km de la playa del Portet, esta impresionante casa de dise\u00f1o ofrece la combinaci\u00f3n perfecta de lujo y comodidad. Situada en una sola...<\/p>\n                                            <\/div>\n                                        <\/div>\n                                        <a href=\"https:\/\/construccionesmarva.com\/es\/projects\/villa-giulia\/\"\n                                           class=\"link-arrow\">Ver proyecto <i class=\"icon ion-ios-arrow-right\"><\/i><\/a>\n                                    <\/div>\n                                <\/div>\n\n\n\t\t\t\t\t\t\t\n                                <div style=\"cursor: pointer;\"\n                                     onclick=\"window.location = 'https:\/\/construccionesmarva.com\/es\/projects\/villa-sauce\/'\"\n                                     class=\"grid-item nuevos-proyectos-a-la-venta js-isotope-item js-grid-item\">\n                                    <div class=\"project-item item-shadow\">\n                                        <img decoding=\"async\" alt=\"Sauce 4\" class=\"img-responsive\"\n                                             src=\"https:\/\/construccionesmarva.com\/wp-content\/uploads\/2026\/03\/Sauce-4-425x573.jpg\">\n                                        <div class=\"project-hover\">\n                                            <div class=\"project-hover-content\">\n                                                <h3 class=\"project-title\">Villa Sauce<\/h3>\n                                                <p class=\"project-description\">Te presentamos la vivienda en construcci\u00f3n en la \u00a0calle Sauce, 4 de Moraira.\r\n\r\nSituada a solo 2,5 km de la playa y del encantador pueblo, esta residencia promete combinar comodidad, estilo y ubicaci\u00f3n privilegiada.\r\n\r\n\r\nCon una distribuci\u00f3n en tres plantas, esta casa ofrece un dise\u00f1o moderno y funcional.\r\n\r\nEn la primera planta, te...<\/p>\n                                            <\/div>\n                                        <\/div>\n                                        <a href=\"https:\/\/construccionesmarva.com\/es\/projects\/villa-sauce\/\"\n                                           class=\"link-arrow\">Ver proyecto <i class=\"icon ion-ios-arrow-right\"><\/i><\/a>\n                                    <\/div>\n                                <\/div>\n\n\n\t\t\t\t\t\t\t\n                                <div style=\"cursor: pointer;\"\n                                     onclick=\"window.location = 'https:\/\/construccionesmarva.com\/es\/projects\/villa-sara\/'\"\n                                     class=\"grid-item nueva-construccion js-isotope-item js-grid-item\">\n                                    <div class=\"project-item item-shadow\">\n                                        <img decoding=\"async\" alt=\"Diseno Sin Titulo 32 1\" class=\"img-responsive\"\n                                             src=\"https:\/\/construccionesmarva.com\/wp-content\/uploads\/2017\/05\/Diseno-sin-titulo-32-1-425x573.png\">\n                                        <div class=\"project-hover\">\n                                            <div class=\"project-hover-content\">\n                                                <h3 class=\"project-title\">Villa Sara<\/h3>\n                                                <p class=\"project-description\">Te damos la bienvenida a esta impresionante villa en primera l\u00ednea de playa, donde el dise\u00f1o y la elegancia se combinan perfectamente con la belleza del mar. Construida en 2023, esta residencia vacacional ofrece una experiencia \u00fanica en la Playa de Calpe, Costa Blanca. Presenta un dise\u00f1o moderno ofreciendo espacios...<\/p>\n                                            <\/div>\n                                        <\/div>\n                                        <a href=\"https:\/\/construccionesmarva.com\/es\/projects\/villa-sara\/\"\n                                           class=\"link-arrow\">Ver proyecto <i class=\"icon ion-ios-arrow-right\"><\/i><\/a>\n                                    <\/div>\n                                <\/div>\n\n\n\t\t\t\t\t\t\t\n                                <div style=\"cursor: pointer;\"\n                                     onclick=\"window.location = 'https:\/\/construccionesmarva.com\/es\/projects\/villa-frigola\/'\"\n                                     class=\"grid-item nueva-construccion js-isotope-item js-grid-item\">\n                                    <div class=\"project-item item-shadow\">\n                                        <img decoding=\"async\" alt=\"DJI 0212 Scaled 1\" class=\"img-responsive\"\n                                             src=\"https:\/\/construccionesmarva.com\/wp-content\/uploads\/2025\/04\/DJI_0212-scaled-1-425x573.jpg\">\n                                        <div class=\"project-hover\">\n                                            <div class=\"project-hover-content\">\n                                                <h3 class=\"project-title\">Villa Frigola<\/h3>\n                                                <p class=\"project-description\">Una vivienda con car\u00e1cter y presencia inconfundible\r\n\r\nDise\u00f1ada por el prestigioso estudio madrile\u00f1o Langarita-Navarro, esta vivienda se presenta como una declaraci\u00f3n de intenciones: una apuesta valiente por una arquitectura contempor\u00e1nea que rompe con los c\u00f3digos tradicionales de la zona.\r\nDesde el primer vistazo, destaca por sus formas curvas, su estructura met\u00e1lica vista...<\/p>\n                                            <\/div>\n                                        <\/div>\n                                        <a href=\"https:\/\/construccionesmarva.com\/es\/projects\/villa-frigola\/\"\n                                           class=\"link-arrow\">Ver proyecto <i class=\"icon ion-ios-arrow-right\"><\/i><\/a>\n                                    <\/div>\n                                <\/div>\n\n\n\t\t\t\t\t\t\t\n                                <div style=\"cursor: pointer;\"\n                                     onclick=\"window.location = 'https:\/\/construccionesmarva.com\/es\/projects\/villa-juliette\/'\"\n                                     class=\"grid-item reformas js-isotope-item js-grid-item\">\n                                    <div class=\"project-item item-shadow\">\n                                        <img decoding=\"async\" alt=\"12 1\" class=\"img-responsive\"\n                                             src=\"https:\/\/construccionesmarva.com\/wp-content\/uploads\/2025\/05\/12-1-425x573.png\">\n                                        <div class=\"project-hover\">\n                                            <div class=\"project-hover-content\">\n                                                <h3 class=\"project-title\">Villa Juliette<\/h3>\n                                                <p class=\"project-description\">Encanto r\u00fastico con vistas al mar\r\nEsta casa de campo, construida a finales del siglo XIX, ha sido cuidadosamente reformada para conservar su esencia y autenticidad. Ubicada en plena naturaleza, en una zona r\u00fastica y tranquila, ofrece la combinaci\u00f3n perfecta entre privacidad, tradici\u00f3n y unas vistas inmejorables al mar.\r\n\r\nLos actuales propietarios,...<\/p>\n                                            <\/div>\n                                        <\/div>\n                                        <a href=\"https:\/\/construccionesmarva.com\/es\/projects\/villa-juliette\/\"\n                                           class=\"link-arrow\">Ver proyecto <i class=\"icon ion-ios-arrow-right\"><\/i><\/a>\n                                    <\/div>\n                                <\/div>\n\n\n\t\t\t\t\t\t\t\n                                <div style=\"cursor: pointer;\"\n                                     onclick=\"window.location = 'https:\/\/construccionesmarva.com\/es\/projects\/villa-annie\/'\"\n                                     class=\"grid-item nueva-construccion js-isotope-item js-grid-item\">\n                                    <div class=\"project-item item-shadow\">\n                                        <img decoding=\"async\" alt=\"03 17 027 Scaled 1\" class=\"img-responsive\"\n                                             src=\"https:\/\/construccionesmarva.com\/wp-content\/uploads\/2025\/01\/03_17_027-scaled-1-425x573.jpg\">\n                                        <div class=\"project-hover\">\n                                            <div class=\"project-hover-content\">\n                                                <h3 class=\"project-title\">Villa Annie<\/h3>\n                                                <p class=\"project-description\">Situada en la exclusiva urbanizaci\u00f3n Rac\u00f3 de Galeno, en Benissa, esta impresionante villa de dise\u00f1o moderno ofrece un estilo de vida excepcional en la Costa Blanca. Su ubicaci\u00f3n privilegiada, rodeada de un entorno natural incomparable, la convierte en una propiedad \u00fanica que combina lujo, amplitud y comodidad.\r\n\r\nDise\u00f1ada por el reconocido...<\/p>\n                                            <\/div>\n                                        <\/div>\n                                        <a href=\"https:\/\/construccionesmarva.com\/es\/projects\/villa-annie\/\"\n                                           class=\"link-arrow\">Ver proyecto <i class=\"icon ion-ios-arrow-right\"><\/i><\/a>\n                                    <\/div>\n                                <\/div>\n\n\n\t\t\t\t\t\t\t\n                                <div style=\"cursor: pointer;\"\n                                     onclick=\"window.location = 'https:\/\/construccionesmarva.com\/es\/projects\/villa-carpi\/'\"\n                                     class=\"grid-item nueva-construccion js-isotope-item js-grid-item\">\n                                    <div class=\"project-item item-shadow\">\n                                        <img decoding=\"async\" alt=\"Diseno Sin Titulo 32 1\" class=\"img-responsive\"\n                                             src=\"https:\/\/construccionesmarva.com\/wp-content\/uploads\/2023\/09\/Diseno-sin-titulo-32-1-425x573.png\">\n                                        <div class=\"project-hover\">\n                                            <div class=\"project-hover-content\">\n                                                <h3 class=\"project-title\">Villa Carpi<\/h3>\n                                                <p class=\"project-description\">Te presentamos esta impresionante villa de estilo moderno, una construcci\u00f3n desde cero que abarca dos plantas y ofrece un total de cuatro dormitorios. Tres de estos dormitorios cuentan con ba\u00f1o en suite, lo que garantiza privacidad y comodidad para los residentes y los invitados. Adem\u00e1s, hay un ba\u00f1o de cortes\u00eda...<\/p>\n                                            <\/div>\n                                        <\/div>\n                                        <a href=\"https:\/\/construccionesmarva.com\/es\/projects\/villa-carpi\/\"\n                                           class=\"link-arrow\">Ver proyecto <i class=\"icon ion-ios-arrow-right\"><\/i><\/a>\n                                    <\/div>\n                                <\/div>\n\n\n\t\t\t\t\t\t\t\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n\t[vc_column_text]<\/p>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/construccionesmarva.com\/es\/proyectos\/\">VER TODOS LOS PROYECTOS<\/a><\/h2>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_row_inner][vc_column_inner][vc_column_text]<\/p>\n<h2 style=\"text-align: center;\">\u00bfQu\u00e9 podemos hacer por ti?<\/h2>\n<p>[\/vc_column_text][vc_separator][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1605205489926{margin-bottom: 20px !important;padding-right: 128px !important;}&#8221;][vc_column_inner width=&#8221;1\/6&#8243;][vc_single_image image=&#8221;28762&#8243; img_size=&#8221;full&#8221; alignment=&#8221;right&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243; css=&#8221;.vc_custom_1598984349663{border-top-width: 2px !important;border-right-width: 2px !important;border-bottom-width: 2px !important;border-right-color: #94143e !important;border-right-style: dashed !important;border-top-color: #94143e !important;border-top-style: dashed !important;border-bottom-color: #94143e !important;border-bottom-style: dashed !important;}&#8221;][vc_column_text css_animation=&#8221;fadeIn&#8221; css=&#8221;.vc_custom_1756296372546{padding-right: 15px !important;}&#8221;]<\/p>\n<h3 style=\"font-size: 1.571rem;\" data-start=\"139\" data-end=\"170\"><strong data-start=\"143\" data-end=\"168\">UBICACI\u00d3N PERFECTA<\/strong><\/h3>\n<p data-start=\"171\" data-end=\"362\">Elegir la parcela adecuada es uno de los pasos m\u00e1s importantes al construir una vivienda. La orientaci\u00f3n, las vistas, el entorno, el acceso y la viabilidad legal marcan una gran diferencia.<\/p>\n<p data-start=\"364\" data-end=\"565\">Conocemos a fondo zonas como Moraira, J\u00e1vea, Calpe, Benissa y otras partes de la Costa Blanca, lo que nos permite asesorarte con seguridad y claridad a la hora de elegir el lugar perfecto para vivir.<\/p>\n<p data-start=\"567\" data-end=\"721\">Y si ya tienes una parcela en mente, estaremos encantados de revisarla contigo para valorar si est\u00e1 bien ubicada y si es adecuada para tu futuro proyecto.<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][vc_single_image image=&#8221;28767&#8243; img_size=&#8221;full&#8221; alignment=&#8221;right&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243; css=&#8221;.vc_custom_1598984365313{border-top-width: 2px !important;border-right-width: 2px !important;border-bottom-width: 2px !important;border-right-color: #94143e !important;border-right-style: dashed !important;border-top-color: #94143e !important;border-top-style: dashed !important;border-bottom-color: #94143e !important;border-bottom-style: dashed !important;}&#8221;][vc_column_text css_animation=&#8221;fadeIn&#8221; css=&#8221;.vc_custom_1756296432378{padding-right: 15px !important;}&#8221;]<\/p>\n<h3 style=\"font-size: 1.571rem;\" data-start=\"728\" data-end=\"759\"><strong data-start=\"732\" data-end=\"757\">PROYECTA TUS IDEAS<\/strong><\/h3>\n<p data-start=\"760\" data-end=\"1065\">Si a\u00fan no tienes arquitecto, podemos ponerte en contacto con profesionales de confianza que te ayudar\u00e1n a dar forma a tus ideas.<br data-start=\"888\" data-end=\"891\" \/>El arquitecto desarrollar\u00e1 un dise\u00f1o preliminar que te permitir\u00e1 visualizar los primeros bocetos de tu futura casa, totalmente adaptados a tus necesidades y estilo de vida.<\/p>\n<p data-start=\"1067\" data-end=\"1391\">Al mismo tiempo, te guiaremos en el proceso constructivo, los plazos estimados y \u2014lo m\u00e1s importante\u2014 el impacto que las decisiones de dise\u00f1o pueden tener en la inversi\u00f3n total.<br data-start=\"1243\" data-end=\"1246\" \/>Alinear el dise\u00f1o con el presupuesto desde el principio ayuda a evitar costes imprevistos, y anticiparse a esto permite tomar mejores decisiones.<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][vc_single_image image=&#8221;28765&#8243; img_size=&#8221;full&#8221; alignment=&#8221;right&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243; css=&#8221;.vc_custom_1598984391020{border-top-width: 2px !important;border-right-width: 2px !important;border-bottom-width: 2px !important;border-right-color: #94143e !important;border-right-style: dashed !important;border-top-color: #94143e !important;border-top-style: dashed !important;border-bottom-color: #94143e !important;border-bottom-style: dashed !important;}&#8221;][vc_column_text css_animation=&#8221;fadeIn&#8221; css=&#8221;.vc_custom_1756296442334{padding-right: 15px !important;}&#8221;]<\/p>\n<h3 style=\"font-size: 1.571rem;\" data-start=\"1398\" data-end=\"1442\"><strong data-start=\"1402\" data-end=\"1440\">PARA HACER REALIDAD TU PROYECTO<\/strong><\/h3>\n<p data-start=\"1443\" data-end=\"1795\">Una vez decides construir tu casa con nosotros, necesitaremos el proyecto final del arquitecto y la licencia de obra correspondiente del Ayuntamiento.<br data-start=\"1593\" data-end=\"1596\" \/>A partir de ah\u00ed, coordinaremos todas las fases del proceso de construcci\u00f3n \u2014desde el movimiento de tierras hasta los acabados finales\u2014 garantizando calidad, eficiencia y cumplimiento de los plazos.<\/p>\n<p data-start=\"1797\" data-end=\"2011\">Nos mantendremos en contacto regular, adapt\u00e1ndonos a tu disponibilidad, para que est\u00e9s siempre informado sobre el avance. Supervisamos de cerca la obra y resolvemos cualquier imprevisto con rapidez y transparencia.<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_row_inner css=&#8221;.vc_custom_1605205494404{padding-right: 128px !important;}&#8221;][vc_column_inner width=&#8221;1\/6&#8243;][vc_single_image image=&#8221;28764&#8243; img_size=&#8221;full&#8221; alignment=&#8221;right&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243; css=&#8221;.vc_custom_1598984447712{border-top-width: 2px !important;border-right-width: 2px !important;border-bottom-width: 2px !important;border-right-color: #94143e !important;border-right-style: dashed !important;border-top-color: #94143e !important;border-top-style: dashed !important;border-bottom-color: #94143e !important;border-bottom-style: dashed !important;}&#8221;][vc_column_text css_animation=&#8221;fadeIn&#8221; css=&#8221;.vc_custom_1756296452949{padding-right: 15px !important;}&#8221;]<\/p>\n<h3 style=\"font-size: 1.571rem;\" data-start=\"2018\" data-end=\"2054\"><strong data-start=\"2022\" data-end=\"2052\">\u00bfSOLO QUIERES REFORMAR?<\/strong><\/h3>\n<p data-start=\"2055\" data-end=\"2209\">Tambi\u00e9n realizamos reformas parciales o integrales para quienes ya tienen vivienda y desean actualizarla, redistribuir espacios o mejorar su eficiencia.<\/p>\n<p data-start=\"2211\" data-end=\"2400\">Te ayudamos a definir el alcance de la reforma, organizamos todos los trabajos necesarios y coordinamos a los profesionales implicados, siempre con plazos y costes claros desde el inicio.<\/p>\n<p data-start=\"2402\" data-end=\"2548\">Nos adaptamos a tus necesidades y al uso que le vayas a dar a la vivienda: como residencia habitual, casa de vacaciones o inversi\u00f3n para alquilar.<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][vc_single_image image=&#8221;28763&#8243; img_size=&#8221;full&#8221; alignment=&#8221;right&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243; css=&#8221;.vc_custom_1598984455913{border-top-width: 2px !important;border-right-width: 2px !important;border-bottom-width: 2px !important;border-right-color: #94143e !important;border-right-style: dashed !important;border-top-color: #94143e !important;border-top-style: dashed !important;border-bottom-color: #94143e !important;border-bottom-style: dashed !important;}&#8221;][vc_column_text css_animation=&#8221;fadeIn&#8221; css=&#8221;.vc_custom_1756296462862{padding-right: 15px !important;}&#8221;]<\/p>\n<h3 style=\"font-size: 1.571rem;\" data-start=\"2555\" data-end=\"2594\"><strong data-start=\"2559\" data-end=\"2592\">GESTIONES Y ACOMPA\u00d1AMIENTO<\/strong><\/h3>\n<p data-start=\"2595\" data-end=\"2898\">Construir una casa no termina cuando se finaliza la obra \u2014todav\u00eda quedan gestiones pr\u00e1cticas, especialmente si no vives aqu\u00ed.<br data-start=\"2720\" data-end=\"2723\" \/>Aunque las licencias t\u00e9cnicas las gestiona tu arquitecto, nosotros te ayudamos con otros tr\u00e1mites administrativos para que puedas poner tu casa en marcha sin complicaciones.<\/p>\n<p data-start=\"2900\" data-end=\"2993\">Estamos aqu\u00ed para facilitar esa \u00faltima etapa, ahorrarte tiempo, estr\u00e9s y viajes innecesarios.<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243;][vc_single_image image=&#8221;28766&#8243; img_size=&#8221;full&#8221; alignment=&#8221;right&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/6&#8243; css=&#8221;.vc_custom_1605205394929{border-top-width: 2px !important;border-right-width: 2px !important;border-bottom-width: 2px !important;border-right-color: #94143e !important;border-right-style: dashed !important;border-top-color: #94143e !important;border-top-style: dashed !important;border-bottom-color: #94143e !important;border-bottom-style: dashed !important;}&#8221;][vc_column_text css_animation=&#8221;fadeIn&#8221; css=&#8221;.vc_custom_1756296476021{padding-right: 15px !important;}&#8221;]<\/p>\n<h3 style=\"font-size: 1.571rem;\">SERVICIO POST-VENTA<\/h3>\n<p data-start=\"3032\" data-end=\"3204\">Nuestro compromiso contigo no termina al acabar la obra. Seguimos estando disponibles para ayudarte con cualquier cosa que surja una vez est\u00e9s instalado en tu nueva casa.<\/p>\n<p data-start=\"3206\" data-end=\"3363\">Ya sea una consulta, un peque\u00f1o ajuste o un imprevisto, nuestro equipo de postventa responde con rapidez y fiabilidad, d\u00e1ndote tranquilidad y apoyo continuo.<\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][vc_empty_space height=&#8221;64px&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css_animation=&#8221;none&#8221; awb_type=&#8221;image&#8221; awb_stretch=&#8221;1&#8243; awb_image_background_position=&#8221;50% 50%&#8221; awb_color=&#8221;rgba(0,0,0,0.42)&#8221; css=&#8221;.vc_custom_1621256888849{background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221; awb_image=&#8221;7383&#8243;][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column css_animation=&#8221;none&#8221; width=&#8221;2\/3&#8243;][vc_single_image image=&#8221;30357&#8243; img_size=&#8221;medium&#8221; alignment=&#8221;center&#8221;][vc_row_inner][vc_column_inner width=&#8221;2\/3&#8243;][vc_images_carousel images=&#8221;31942,31582,31584&#8243; img_size=&#8221;full&#8221; speed=&#8221;3000&#8243; autoplay=&#8221;yes&#8221; wrap=&#8221;yes&#8221; css_animation=&#8221;slideInLeft&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243; offset=&#8221;vc_hidden-md vc_hidden-sm vc_hidden-xs&#8221;][vc_empty_space height=&#8221;75px&#8221;][vc_single_image image=&#8221;30315&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css_animation=&#8221;slideInRight&#8221;][vc_column_text css_animation=&#8221;slideInRight&#8221; css=&#8221;.vc_custom_1756297069459{margin-right: 50px !important;margin-left: 50px !important;background-color: #ffffff !important;background-position: center !important;background-repeat: no-repeat !important;background-size: contain !important;border-radius: 10px !important;}&#8221;]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000; font-size: 1.714rem;\"><a href=\"https:\/\/www.estateagentsmoraira.com\/\" target=\"_blank\" rel=\"noopener\"><strong>Pincha aqu\u00ed<\/strong><\/a><\/span><\/p>\n<p>[\/vc_column_text][\/vc_column_inner][vc_column_inner width=&#8221;1\/3&#8243; offset=&#8221;vc_hidden-lg&#8221;][vc_single_image image=&#8221;30315&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css_animation=&#8221;slideInRight&#8221;][vc_column_text css_animation=&#8221;slideInRight&#8221; css=&#8221;.vc_custom_1756297080935{margin-right: 50px !important;margin-left: 50px !important;background-color: #ffffff !important;background-position: center !important;background-repeat: no-repeat !important;background-size: contain !important;border-radius: 10px !important;}&#8221;]<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000; font-size: 1.714rem;\"><a href=\"https:\/\/www.estateagentsmoraira.com\/\"><strong>Pincha aqu\u00ed<\/strong><\/a><\/span><\/p>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/6&#8243; css=&#8221;.vc_custom_1621251516352{background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content_no_spaces&#8221;][vc_column]\n\n    <section\n            class=\"section-clients section bg-dots  \"  >\n        <div class=\"container\">\n            <h2 class=\"section-title\">La experiencia de nuestros clientes<\/h2>\n            <div class=\"client-carousel owl-carousel\">\n\t\t\t\t\n                        <div class=\"client-carousel-item\">\n\t\t\t\t\t\t\t                                <img decoding=\"async\" alt=\"Victoria 1\" class=\"client-img\" src=\"https:\/\/construccionesmarva.com\/wp-content\/uploads\/2021\/03\/victoria-1.png\">\n\n\t\t\t\t\t\t\t\t                            <div class=\"client-box\">\n\t\t\t\t\t\t\t\t                                <div class=\"client-title\">\n\t\t\t\t\t\t\t\t\t                                        <span class=\"client-name\">Victoria y Erik<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <span\n                                                class=\"client-company\">  Proyecto: Villa Victoria<\/span>\n\t\t\t\t\t\t\t\t\t\t                                <\/div>\n                                <p class=\"client-description\">\"Desde nuestra primera reuni\u00f3n para comentar el proyecto hasta el d\u00eda de hoy m\u00e1s de \n  un a\u00f1o despu\u00e9s, Marva y todos sus directivos nos han impresionado por su integridad y \n  profesionalismo en todos los sentidos. Realmente se tomaron nuestro proyecto como si fuera \n  suyo, haci\u00e9ndonos sentir qu\u00e9 era tan importante para ellos como para nosotros.\"<\/p>\n                            <\/div>\n                        <\/div>\n\t\t\t\t\t\n                        <div class=\"client-carousel-item\">\n\t\t\t\t\t\t\t                                <img decoding=\"async\" alt=\"2 1 Scaled\" class=\"client-img\" src=\"https:\/\/construccionesmarva.com\/wp-content\/uploads\/2021\/03\/2-1-scaled.jpg\">\n\n\t\t\t\t\t\t\t\t                            <div class=\"client-box\">\n\t\t\t\t\t\t\t\t                                <div class=\"client-title\">\n\t\t\t\t\t\t\t\t\t                                        <span class=\"client-name\">Hans y Annika<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <span\n                                                class=\"client-company\">Proyecto: Villa Annika<\/span>\n\t\t\t\t\t\t\t\t\t\t                                <\/div>\n                                <p class=\"client-description\">\"Construir en Espa\u00f1a es realmente una aventura. Pero con Construcciones Marva una aventura que t\u00fa, incluso como extranjero, puedes emprender sin miedo. Es m\u00e1s, despu\u00e9s de completar la aventura de la construcci\u00f3n, usted y la familia Mart\u00ednez tienen inmediatamente sus primeros amigos locales muy agradables, con quienes siempre es un placer volver a verlos.\"<\/p>\n                            <\/div>\n                        <\/div>\n\t\t\t\t\t\n                        <div class=\"client-carousel-item\">\n\t\t\t\t\t\t\t                                <img decoding=\"async\" alt=\"3 Scaled\" class=\"client-img\" src=\"https:\/\/construccionesmarva.com\/wp-content\/uploads\/2021\/03\/3-scaled.jpg\">\n\n\t\t\t\t\t\t\t\t                            <div class=\"client-box\">\n\t\t\t\t\t\t\t\t                                <div class=\"client-title\">\n\t\t\t\t\t\t\t\t\t                                        <span class=\"client-name\">Russell<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <span\n                                                class=\"client-company\">Proyecto: Villa Russell<\/span>\n\t\t\t\t\t\t\t\t\t\t                                <\/div>\n                                <p class=\"client-description\">\"El equipo Marva hizo un excelente trabajo al entregar lo que pedimos en nuestra nueva casa en Moraira y en un horario relativamente apretado. Nos mantuvo bien informados mientras est\u00e1bamos en el Reino Unido y el buen nivel de comunicaci\u00f3n entre nosotros signific\u00f3 que entendi\u00f3 lo que quer\u00edamos lo suficientemente bien como para tomar decisiones por nosotros mientras est\u00e1bamos ausentes y no pod\u00edamos estar en el lugar para hacer la llamada nosotros mismos. No podr\u00edamos recomendarlos lo suficiente.\"<\/p>\n                            <\/div>\n                        <\/div>\n\t\t\t\t\t\n                        <div class=\"client-carousel-item\">\n\t\t\t\t\t\t\t                                <img decoding=\"async\" alt=\"1 Scaled\" class=\"client-img\" src=\"https:\/\/construccionesmarva.com\/wp-content\/uploads\/2021\/03\/1-scaled.jpg\">\n\n\t\t\t\t\t\t\t\t                            <div class=\"client-box\">\n\t\t\t\t\t\t\t\t                                <div class=\"client-title\">\n\t\t\t\t\t\t\t\t\t                                        <span class=\"client-name\">Frans<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <span\n                                                class=\"client-company\">Proyecto: Villa Frans<\/span>\n\t\t\t\t\t\t\t\t\t\t                                <\/div>\n                                <p class=\"client-description\">\"Comprarle una casa a Marva no es una transacci\u00f3n, sino entablar una relaci\u00f3n en la que el equipo de Marva se mantiene comprometido a ocuparse de muchas cosas que te dan tiempo para disfrutar de tu casa. Hacer realidad el sue\u00f1o del cliente es la visi\u00f3n del equipo de Marva. Pero no se detiene ah\u00ed. Mantener vivo el sue\u00f1o es lo que realmente hacen. La estancia comprometida con un disfrute sin preocupaciones del sue\u00f1o.\"<\/p>\n                            <\/div>\n                        <\/div>\n\t\t\t\t\t\n                        <div class=\"client-carousel-item\">\n\t\t\t\t\t\t\t                                <img decoding=\"async\" alt=\"4 1 Scaled\" class=\"client-img\" src=\"https:\/\/construccionesmarva.com\/wp-content\/uploads\/2021\/03\/4-1-scaled.jpg\">\n\n\t\t\t\t\t\t\t\t                            <div class=\"client-box\">\n\t\t\t\t\t\t\t\t                                <div class=\"client-title\">\n\t\t\t\t\t\t\t\t\t                                        <span class=\"client-name\">Herman y Greet<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <span\n                                                class=\"client-company\">Proyecto: Villa Greet<\/span>\n\t\t\t\t\t\t\t\t\t\t                                <\/div>\n                                <p class=\"client-description\">\"Tuvimos una experiencia maravillosa con el equipo de Construcciones Marva. Esta empresa familiar con mucha experiencia, es muy amigable, alegre y abierta a la hora de pensar junto al cliente los diferentes dise\u00f1os de la futura casa. Recomiendo encarecidamente trabajar con Marva, ya que poseen mucho conocimiento del sector de la construcci\u00f3n, y su trabajo tanto para obra nueva como para reforma es excelente.\"<\/p>\n                            <\/div>\n                        <\/div>\n\t\t\t\t\t\n                        <div class=\"client-carousel-item\">\n\t\t\t\t\t\t\t                                <img decoding=\"async\" alt=\"6 1 Scaled\" class=\"client-img\" src=\"https:\/\/construccionesmarva.com\/wp-content\/uploads\/2021\/03\/6-1-scaled.jpg\">\n\n\t\t\t\t\t\t\t\t                            <div class=\"client-box\">\n\t\t\t\t\t\t\t\t                                <div class=\"client-title\">\n\t\t\t\t\t\t\t\t\t                                        <span class=\"client-name\">Johnny y Karin<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <span\n                                                class=\"client-company\">Proyecto: Villa Karin<\/span>\n\t\t\t\t\t\t\t\t\t\t                                <\/div>\n                                <p class=\"client-description\">\"El equipo de Marva es \u00fanico. Siempre dicen \u00absi algo anda mal lo arreglaremos\u00bb. Y lo hacen una y otra vez si es necesario. Gracias ha esa determinaci\u00f3n, ahora disfrutamos de nuestra villa desde hace un a\u00f1o y vivimos felices, porque nuestro sue\u00f1o se ha hecho realidad y obtuvimos lo que quer\u00edamos.\"<\/p>\n                            <\/div>\n                        <\/div>\n\t\t\t\t\t\n                        <div class=\"client-carousel-item\">\n\t\t\t\t\t\t\t                                <img decoding=\"async\" alt=\"Villa Nicole Filtro Negro\" class=\"client-img\" src=\"https:\/\/construccionesmarva.com\/wp-content\/uploads\/2017\/05\/Villa-Nicole-filtro-negro.png\">\n\n\t\t\t\t\t\t\t\t                            <div class=\"client-box\">\n\t\t\t\t\t\t\t\t                                <div class=\"client-title\">\n\t\t\t\t\t\t\t\t\t                                        <span class=\"client-name\">Sandra y David<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <span\n                                                class=\"client-company\">  Proyecto: Villa Sandra<\/span>\n\t\t\t\t\t\t\t\t\t\t                                <\/div>\n                                <p class=\"client-description\">\"Los procesos y la calidad de la construcci\u00f3n de Marva son \n  extremadamente altos. Cumplieron los plazos y la construcci\u00f3n se entreg\u00f3 a tiempo y con \n  una alta especificaci\u00f3n. Adem\u00e1s Marva ha respondido muy bien a problemas menores tras la \n  finalizaci\u00f3n del proyecto y lo continuan haciendo a un nivel muy alto.\"<\/p>\n                            <\/div>\n                        <\/div>\n\t\t\t\t\t\n                        <div class=\"client-carousel-item\">\n\t\t\t\t\t\t\t                                <img decoding=\"async\" alt=\"La Jijonenca Testimonio 1\" class=\"client-img\" src=\"https:\/\/construccionesmarva.com\/wp-content\/uploads\/2021\/03\/La-jijonenca-testimonio-1.jpg\">\n\n\t\t\t\t\t\t\t\t                            <div class=\"client-box\">\n\t\t\t\t\t\t\t\t                                <div class=\"client-title\">\n\t\t\t\t\t\t\t\t\t                                        <span class=\"client-name\">Raquel, Conchi y Toni<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                                        <span\n                                                class=\"client-company\">Proyecto: Helader\u00eda La Jijonenca<\/span>\n\t\t\t\t\t\t\t\t\t\t                                <\/div>\n                                <p class=\"client-description\">\"Mas tarde, pasados unos a\u00f1os, cambiamos nuestro negocio (La Helader\u00eda La Jijonenca de Benissa) de local, y como no, sin dudarlo ni cuestionarnos en ning\u00fan momento volvimos a contactar con ellos, aunque en esta ocasi\u00f3n se tuvieron que adaptar ellos m\u00e1s a las necesidades de nuestro negocio, as\u00ed y todo quedamos otra vez encantados con el resultado. Mil gracias familia Marva por todo.\"<\/p>\n                            <\/div>\n                        <\/div>\n\t\t\t\t\t            <\/div>\n            <div class=\"partner-carousel owl-carousel\">\n\t\t\t\t                        <div class=\"partner-carousel-item\">\n\n\t\t\t\t\t\t            <\/div>\n        <\/div>\n    <\/section>\n\n\t[\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221;][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][vc_column_text]<\/p>\n<h3>Nuestra misi\u00f3n es<br \/>\n<span class=\"text-primary\">hacer posible<\/span>\u00a0el hogar so\u00f1ado por nuestros clientes.<\/h3>\n<p><strong style=\"color: black;\">Somos una empresa constructora con m\u00e1s de 50 a\u00f1os de experiencia en el sector residencial de lujo de la Costa Blanca, Benissa, Calpe, Xabia y Teulada-Moraira.<\/strong><\/p>\n<p><strong style=\"color: black;\">Si quieres una nueva casa o reformar la que ya tienes, te mostramos c\u00f3mo lo podemos hacer realidad definiendo de manera muy precisa el proceso de construcci\u00f3n. Pero antes de nada, queremos conocerte de verdad y que t\u00fa nos conozcas a nosotros, para darte exactamente lo que quieres.<\/strong>[\/vc_column_text][vc_row_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<ul class=\"service-list\">\n<li><a href=\"https:\/\/construccionesmarva.com\/es\/sobre-marva\/\">01. CONOCE MARVA<\/a><\/li>\n<li><a href=\"https:\/\/construccionesmarva.com\/es\/servicios\/\">02. NUESTROS SERVICIOS<\/a><\/li>\n<li><a href=\"https:\/\/construccionesmarva.com\/es\/proyectos\/\">03. PROYECTOS<\/a><\/li>\n<li><a href=\"https:\/\/construccionesmarva.com\/es\/noticias\/\">04. NOTICIAS<\/a><\/li>\n<li><a href=\"https:\/\/construccionesmarva.com\/es\/contacto\/\">05. CONTACTO<\/a><\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_single_image image=&#8221;28882&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;28883&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221; css=&#8221;.vc_custom_1606123418593{padding-top: -64px !important;padding-right: -64px !important;padding-bottom: -64px !important;padding-left: -64px !important;}&#8221;][vc_column_text]<\/p>\n<h3>M\u00e1s de<br \/>\n<span class=\"text-primary\">50 a\u00f1os<\/span>\u00a0de experiencia y compromiso.<\/h3>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; css=&#8221;.vc_custom_1747647148761{background-image: url(https:\/\/construccionesmarva.com\/wp-content\/uploads\/2020\/08\/2017-12-21-PHOTO-00002499.jpg?id=6624) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;1\/6&#8243;][\/vc_column][vc_column width=&#8221;2\/3&#8243;][vc_empty_space][vc_row_inner disable_element=&#8221;yes&#8221;][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;28739&#8243; img_size=&#8221;full&#8221; alignment=&#8221;center&#8221;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][vc_column_text]<\/p>\n<h2><span style=\"color: #ffffff;\">Los 7 errores m\u00e1s frecuentes que debes evitar al comprar tu casa de lujo en la Costa Blanca<\/span><\/h2>\n<p>[\/vc_column_text][vc_column_text]<\/p>\n<h5 class=\"p1\"><a href=\"https:\/\/construccionesmarva.com\/ebook\/\"><span style=\"color: #ffffff;\"><strong>Descarga el EBOOK GRATIS<\/strong><\/span><\/a><\/h5>\n<hr \/>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/6&#8243;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space]\n\n    <section    >\n        <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col-md-3\">\n                    <div class=\"section-info\">\n                        <div class=\"title-hr\"><\/div>\n                        <div class=\"info-title\">Localizaci\u00f3n &amp; Contacto<\/div>\n                    <\/div>\n                <\/div>\n                <div class=\"col-md-9\">\n                    <div class=\"row-contact row\">\n                        <div class=\"col-contact col-lg-6\">\n                            <h3 class=\"contact-title contact-top\">Oficinas en Moraira<\/h3>\n                            <p class=\"contact-address text-muted\"><strong><\/strong><\/p>\n\t\t\t\t\t\t\t                                    <p class=\"contact-row\">C\/ Doctor Calatayud, 49<br>\n03724 Moraira<br>\nAlicante - Espa\u00f1a<\/p>\n\t\t\t\t\t\t\t\t                                    <p class=\"contact-row\"><strong class=\"text-dark\">Email:<\/strong> <a href=\"mailto:veronica@construccionesmarva.com\" target=\"_blank\" rel=\"nofollow\">veronica@construccionesmarva.com<\/a>\n<\/p>\n\t\t\t\t\t\t\t\t                        <\/div>\n                        <div class=\"col-contact col-lg-6\">\n                            <p class=\"contact-top\"><strong\n                                        class=\"text-muted\">Ll\u00e1manos:<\/strong><\/p>\n                           <p class=\"phone-lg text-dark\">\t\t\t\t\t\t\t\t\t<a id=\"tlf-home_contacto\" href=\"tel:(+34)965744106\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t\t\t\t\t(+34) 96 574 41 06\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/p>\n                            <p class=\"text-muted\"><strong class=\"text-dark\">Horario de Atenci\u00f3n al Cliente<\/strong><br>\n\t\t\t\t\t\t\t\tLunes - Viernes : 09h00 - 18h00<\/p>\n                            <div class=\"text-muted\"><strong\n                                        class=\"text-dark\">S\u00edguenos en Redes Sociales<\/strong><br>\n                                <div class=\"contact-social social-list\">\n\n\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/www.facebook.com\/construccionesmarva\/\" class=\"icon  icon ion-social-facebook\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><\/a>\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/twitter.com\/infomarva?lang=es\" class=\"icon  icon ion-social-twitter\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><\/a>\n\t\t\t\t\t\t\t\t\t\t                                            <a href=\"https:\/\/www.linkedin.com\/public-profile\/in\/construcciones-marva-sl-8849b333\/\" class=\"icon  icon ion-social-linkedin\" target=\"_blank\" rel=\"nofollow noopener noreferrer\"><\/a>\n\t\t\t\t\t\t\t\t\t\t                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n\n\n\t[\/vc_column][\/vc_row][vc_row][vc_column]    <section\n            class=\"section-message section \"  >\n        <div class=\"container\">\n            <div class=\"row\">\n                <div class=\"col-md-3\">\n                    <div class=\"section-info\">\n                        <div class=\"title-hr\"><\/div>\n                        <div class=\"info-title\">Escr\u00edbenos un mensaje<\/div>\n                    <\/div>\n                <\/div>\n                <div class=\"col-md-9\">\n\t\t\t\t\t\n\t\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f29851-o1\" lang=\"es\" dir=\"ltr\" data-wpcf7-id=\"29851\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/29828#wpcf7-f29851-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"29851\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.1\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f29851-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<div class=\"form-group col-sm-6 col-lg-4\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nombre*\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-group col-sm-6 col-lg-4\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Correo electr\u00f3nico*\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-group col-sm-6 col-lg-4\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Tel\u00e9fono*\" value=\"\" type=\"tel\" name=\"your-phone\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-group col-sm-6 col-lg-4\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" placeholder=\"Asunto (Opcional)\" value=\"\" type=\"text\" name=\"your-subject\" \/><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-group col-sm-12\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Mensaje*\" name=\"your-message\"><\/textarea><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"form-group col-sm-12 aceptacion\">\n\t\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"politica-privacidad\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"politica-privacidad\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">He le\u00eddo y acepto la <a href=\"\/es\/politica-privacidad\/\" target=\"_blank\" rel=\"nofollow\" style=\"color:#000;\">pol\u00edtica de privacidad<\/a><\/span><\/label><\/span><\/span><\/span>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"col-sm-12\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn-upper btn-yellow btn\" type=\"submit\" value=\"Enviar Mensaje\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"54\"\/><script>document.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );<\/script><\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t\t\t\t                <\/div>\n            <\/div>\n        <\/div>\n    <\/section>\n\n\n\t[\/vc_column][\/vc_row][vc_row][vc_column]\n\n    <div data-lat=\"\n\t38.689005\"\n         data-lng=\"0.134730\" id=\"map\" class=\"map\">\n\n\t\t            <div class=\"map-title\">\n\n                <div class=\"brand\" href=\"#\">\n\t\t\t\t\t                    <div class=\"brand-info\">\n                        <div class=\"brand-name\">Marva<\/div>\n                        <div class=\"brand-text\">Construcciones &amp; Ventas<\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n            <p class=\"map-address\"><\/p>\n\t\t\t\n\t\t\t                <p class=\"gmap-open\">\n                    <a\n                            href=\"https:\/\/www.google.com\/maps\/place\/Marva+Construcciones\/@38.6883267,0.131973,17z\/data=!4m8!1m2!2m1!1sC%2F+Doctor+Calatayud,+49+03724+Moraira+Alicante+-+Spain!3m4!1s0x129e07c945b6bca9:0xf4c0c656848bc9db!8m2!3d38.6888199!4d0.1346909\"\n                            target=\"_blank\">Abrir en Google Maps<\/a><\/p>\n\n\t\t\t\n\t\t\n    <\/div>\n\n\t\n    <script>\n\n\n        function initialize() {\n\n            var contentString = '<div class=\"map-info\">'\n                + jQuery(\"#map\").html() +\n                '<\/div>';\n\n\n            var mapOptions = {\n                zoom: 8, \/\/ Change zoom here\n                center: mapLocation,\n                scrollwheel: false,\n\n                styles: [\n    {\n        \"featureType\": \"all\",\n        \"elementType\": \"geometry.fill\",\n        \"stylers\": [\n            {\n                \"weight\": \"2.00\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"all\",\n        \"elementType\": \"geometry.stroke\",\n        \"stylers\": [\n            {\n                \"color\": \"#9c9c9c\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"all\",\n        \"elementType\": \"labels.text\",\n        \"stylers\": [\n            {\n                \"visibility\": \"on\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"landscape\",\n        \"elementType\": \"all\",\n        \"stylers\": [\n            {\n                \"color\": \"#f2f2f2\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"landscape\",\n        \"elementType\": \"geometry.fill\",\n        \"stylers\": [\n            {\n                \"color\": \"#ffffff\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"landscape.man_made\",\n        \"elementType\": \"geometry.fill\",\n        \"stylers\": [\n            {\n                \"color\": \"#ffffff\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"poi\",\n        \"elementType\": \"all\",\n        \"stylers\": [\n            {\n                \"visibility\": \"off\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"road\",\n        \"elementType\": \"all\",\n        \"stylers\": [\n            {\n                \"saturation\": -100\n            },\n            {\n                \"lightness\": 45\n            }\n        ]\n    },\n    {\n        \"featureType\": \"road\",\n        \"elementType\": \"geometry.fill\",\n        \"stylers\": [\n            {\n                \"color\": \"#eeeeee\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"road\",\n        \"elementType\": \"labels.text.fill\",\n        \"stylers\": [\n            {\n                \"color\": \"#7b7b7b\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"road\",\n        \"elementType\": \"labels.text.stroke\",\n        \"stylers\": [\n            {\n                \"color\": \"#ffffff\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"road.highway\",\n        \"elementType\": \"all\",\n        \"stylers\": [\n            {\n                \"visibility\": \"simplified\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"road.arterial\",\n        \"elementType\": \"labels.icon\",\n        \"stylers\": [\n            {\n                \"visibility\": \"off\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"transit\",\n        \"elementType\": \"all\",\n        \"stylers\": [\n            {\n                \"visibility\": \"off\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"water\",\n        \"elementType\": \"all\",\n        \"stylers\": [\n            {\n                \"color\": \"#46bcec\"\n            },\n            {\n                \"visibility\": \"on\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"water\",\n        \"elementType\": \"geometry.fill\",\n        \"stylers\": [\n            {\n                \"color\": \"#c8d7d4\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"water\",\n        \"elementType\": \"labels.text.fill\",\n        \"stylers\": [\n            {\n                \"color\": \"#070707\"\n            }\n        ]\n    },\n    {\n        \"featureType\": \"water\",\n        \"elementType\": \"labels.text.stroke\",\n        \"stylers\": [\n            {\n                \"color\": \"#ffffff\"\n            }\n        ]\n    }\n]\n            };\n\n            map = new google.maps.Map(document.getElementById('map'),\n                mapOptions);\n            var infowindow = new google.maps.InfoWindow({\n                content: contentString,\n            });\n\n\t\t\t            marker = new google.maps.Marker({\n                map: map,\n                draggable: true,\n                title: 'bauhaus', \/\/change title here\n                animation: google.maps.Animation.DROP,\n                position: mapLocation\n            });\n\t\t\t            google.maps.event.addListener(marker, 'click', function () {\n                infowindow.open(map, marker);\n            });\n\n\n            infowindow.open(map, marker);\n\n        }\n\n\n    <\/script>\n\n\t[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_column_inner width=&#8221;1\/6&#8243; css=&#8221;.vc_custom_1598984349663{border-top-width: 2px !important;border-right-width: 2px !important;border-bottom-width: 2px !important;border-right-color: #94143e [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":1,"comment_status":"closed","ping_status":"closed","template":"template-fullwidth.php","meta":{"_joinchat":[],"footnotes":""},"class_list":["post-29828","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Construcciones Marva: villas y casas de obra nueva<\/title>\n<meta name=\"description\" content=\"Descubre las excepcionales villas de obra nueva de Construcciones Marva. Nuestra experiencia en construcci\u00f3n nos convierte en la mejor constructora\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/construccionesmarva.com\/es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Construcciones Marva: villas y casas de obra nueva\" \/>\n<meta property=\"og:description\" content=\"Descubre las excepcionales villas de obra nueva de Construcciones Marva. Nuestra experiencia en construcci\u00f3n nos convierte en la mejor constructora\" \/>\n<meta property=\"og:url\" content=\"https:\/\/construccionesmarva.com\/es\/\" \/>\n<meta property=\"og:site_name\" content=\"Marva\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-25T08:29:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/construccionesmarva.com\/wp-content\/webp-express\/webp-images\/uploads\/2022\/02\/Logotipos_Marva-10-e1644950568634.png.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1906\" \/>\n\t<meta property=\"og:image:height\" content=\"577\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/construccionesmarva.com\/wp-content\/webp-express\/webp-images\/uploads\/2022\/02\/Logotipos_Marva-10-e1644950568634.png.webp\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/construccionesmarva.com\/es\/\",\"url\":\"https:\/\/construccionesmarva.com\/es\/\",\"name\":\"Construcciones Marva: villas y casas de obra nueva\",\"isPartOf\":{\"@id\":\"https:\/\/construccionesmarva.com\/es\/#website\"},\"datePublished\":\"2025-04-16T10:38:49+00:00\",\"dateModified\":\"2025-09-25T08:29:04+00:00\",\"description\":\"Descubre las excepcionales villas de obra nueva de Construcciones Marva. Nuestra experiencia en construcci\u00f3n nos convierte en la mejor constructora\",\"breadcrumb\":{\"@id\":\"https:\/\/construccionesmarva.com\/es\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/construccionesmarva.com\/es\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/construccionesmarva.com\/es\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/construccionesmarva.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Portada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/construccionesmarva.com\/es\/#website\",\"url\":\"https:\/\/construccionesmarva.com\/es\/\",\"name\":\"Marva\",\"description\":\"Construction and housing sales\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/construccionesmarva.com\/es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Construcciones Marva: villas y casas de obra nueva","description":"Descubre las excepcionales villas de obra nueva de Construcciones Marva. Nuestra experiencia en construcci\u00f3n nos convierte en la mejor constructora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/construccionesmarva.com\/es\/","og_locale":"es_ES","og_type":"article","og_title":"Construcciones Marva: villas y casas de obra nueva","og_description":"Descubre las excepcionales villas de obra nueva de Construcciones Marva. Nuestra experiencia en construcci\u00f3n nos convierte en la mejor constructora","og_url":"https:\/\/construccionesmarva.com\/es\/","og_site_name":"Marva","article_modified_time":"2025-09-25T08:29:04+00:00","og_image":[{"width":1906,"height":577,"url":"https:\/\/construccionesmarva.com\/wp-content\/webp-express\/webp-images\/uploads\/2022\/02\/Logotipos_Marva-10-e1644950568634.png.webp","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/construccionesmarva.com\/wp-content\/webp-express\/webp-images\/uploads\/2022\/02\/Logotipos_Marva-10-e1644950568634.png.webp","twitter_misc":{"Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/construccionesmarva.com\/es\/","url":"https:\/\/construccionesmarva.com\/es\/","name":"Construcciones Marva: villas y casas de obra nueva","isPartOf":{"@id":"https:\/\/construccionesmarva.com\/es\/#website"},"datePublished":"2025-04-16T10:38:49+00:00","dateModified":"2025-09-25T08:29:04+00:00","description":"Descubre las excepcionales villas de obra nueva de Construcciones Marva. Nuestra experiencia en construcci\u00f3n nos convierte en la mejor constructora","breadcrumb":{"@id":"https:\/\/construccionesmarva.com\/es\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/construccionesmarva.com\/es\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/construccionesmarva.com\/es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/construccionesmarva.com\/es\/"},{"@type":"ListItem","position":2,"name":"Portada"}]},{"@type":"WebSite","@id":"https:\/\/construccionesmarva.com\/es\/#website","url":"https:\/\/construccionesmarva.com\/es\/","name":"Marva","description":"Construction and housing sales","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/construccionesmarva.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/construccionesmarva.com\/es\/wp-json\/wp\/v2\/pages\/29828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/construccionesmarva.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/construccionesmarva.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/construccionesmarva.com\/es\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/construccionesmarva.com\/es\/wp-json\/wp\/v2\/comments?post=29828"}],"version-history":[{"count":18,"href":"https:\/\/construccionesmarva.com\/es\/wp-json\/wp\/v2\/pages\/29828\/revisions"}],"predecessor-version":[{"id":32564,"href":"https:\/\/construccionesmarva.com\/es\/wp-json\/wp\/v2\/pages\/29828\/revisions\/32564"}],"wp:attachment":[{"href":"https:\/\/construccionesmarva.com\/es\/wp-json\/wp\/v2\/media?parent=29828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}